{"id":32573,"date":"2025-03-29T10:32:02","date_gmt":"2025-03-29T10:32:02","guid":{"rendered":"https:\/\/lifelonghearing.com\/cs\/?page_id=32573"},"modified":"2026-03-03T08:57:13","modified_gmt":"2026-03-03T08:57:13","slug":"ambasadori-sluchu","status":"publish","type":"page","link":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/","title":{"rendered":"Ambasadori Sluchu"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:80px;--awb-padding-right:20px;--awb-padding-bottom:80px;--awb-padding-left:20px;--awb-padding-top-medium:60px;--awb-padding-right-medium:20px;--awb-padding-bottom-medium:60px;--awb-padding-left-medium:20px;--awb-padding-top-small:50px;--awb-padding-right-small:20px;--awb-padding-bottom-small:50px;--awb-padding-left-small:20px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-margin-top-medium:0px;--awb-margin-bottom-medium:0px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:10px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:10px;--awb-spacing-left-large:0px;--awb-width-medium:100%;--awb-order-medium:0;--awb-margin-top-medium:0;--awb-spacing-right-medium:1.92%;--awb-margin-bottom-medium:40px;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:30px;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"400\" title=\"hearing-ambassadors-featured-600&#215;400\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/hearing-ambassadors-featured-600x400-1.jpg\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/hearing-ambassadors-featured-600x400-1.jpg\" alt class=\"lazyload img-responsive wp-image-32576\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27400%27%20viewBox%3D%270%200%20600%20400%27%3E%3Crect%20width%3D%27600%27%20height%3D%27400%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/hearing-ambassadors-featured-600x400-1-200x133.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/hearing-ambassadors-featured-600x400-1-400x267.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/hearing-ambassadors-featured-600x400-1.jpg 600w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:10px;--awb-spacing-right-large:40px;--awb-margin-bottom-large:10px;--awb-spacing-left-large:40px;--awb-width-medium:100%;--awb-order-medium:0;--awb-margin-top-medium:0;--awb-spacing-right-medium:1.92%;--awb-margin-bottom-medium:0;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:0;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:0;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:#3d3b3b;--awb-margin-top:0px;--awb-margin-top-small:0px;--awb-font-size:45px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;DM Serif Text&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;--fontSize:45;line-height:1.4;\"><h1>Na\u0161i sluchov\u00ed ambasado\u0159i jsou ochotni se s v\u00e1mi pod\u011blit o sv\u00e9 zku\u0161enosti!<\/h1><\/h1><\/div><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"--awb-font-size:var(--awb-typography4-font-size);--awb-line-height:var(--awb-typography4-line-height);--awb-letter-spacing:var(--awb-typography4-letter-spacing);--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:#515151;--awb-text-font-family:var(--awb-typography4-font-family);--awb-text-font-weight:var(--awb-typography4-font-weight);--awb-text-font-style:var(--awb-typography4-font-style);\"><p>Za\u010d\u00edn\u00e1te p\u0159em\u00fd\u0161let o \u0159e\u0161en\u00ed va\u0161ich sluchov\u00fdch probl\u00e9m\u016f nebo stoj\u00edte t\u011bsn\u011b p\u0159ed rozhodnut\u00edm pro kochle\u00e1rn\u00ed implant\u00e1t? Hled\u00e1te to spr\u00e1vn\u00e9 \u0159e\u0161en\u00ed pro va\u0161e d\u00edt\u011b? Pot\u0159ebujete tipy pro \u017eivot s kochle\u00e1rn\u00edm implant\u00e1tem? Zaj\u00edm\u00e1 v\u00e1s technologie kochle\u00e1rn\u00edch implant\u00e1t\u016f? Kontaktujte na\u0161e sluchov\u00e9 ambasadory a zeptejte se jich p\u0159\u00edmo.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:10px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:10px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two ys-margin\" style=\"--awb-text-color:#3d3b3b;--awb-margin-top:0px;--awb-margin-bottom:30px;--awb-font-size:45px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;DM Serif Text&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;--fontSize:45;line-height:1.4;\">Kontaktovat na\u0161e sluchov\u00e9 ambasadory.<\/h2><\/div><div class=\"fusion-post-cards fusion-post-cards-1 fusion-grid-archive fusion-grid-columns-3\" style=\"--awb-column-spacing:20px;--awb-dots-align:center;--awb-columns:3;--awb-active-filter-border-size:3px;--awb-filters-height:36px;--awb-row-spacing:20px;--awb-columns-medium:33.3333%;\"><ul class=\"fusion-grid fusion-grid-3 fusion-flex-align-items-stretch fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/jana\/\" aria-label=\"Jana\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2026\/02\/Jana-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Jana<\/p>\n<\/div><div class=\"fusion-text fusion-text-3 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Matka jednostrann\u00e9ho u\u017eivatele (prav\u00e1 strana)\nRONDO 3\nPlze\u0148<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/jana\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/martin\/\" aria-label=\"Martin\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/DSCF5321-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Martin<\/p>\n<\/div><div class=\"fusion-text fusion-text-5 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Jsem oboustrann\u011b implantovan\u00fd u\u017eivatel kochle\u00e1rn\u00edho implant\u00e1tu. V 18 letech jsem se rozhodl pro kochle\u00e1rn\u00ed implant\u00e1t. Zl\u00edn<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/martin\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/lenka\/\" aria-label=\"Lenka\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Lenka-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-6 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Lenka<\/p>\n<\/div><div class=\"fusion-text fusion-text-7 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Jsem maminka nesly\u0161\u00edc\u00ed dcery Evelyn. Pou\u017e\u00edv\u00e1me RONDO 3. Ji\u010d\u00edn<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/lenka\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/michaela\/\" aria-label=\"Michaela\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Michaela-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-8 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Michaela<\/p>\n<\/div><div class=\"fusion-text fusion-text-9 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Jsem oboustrann\u00fd u\u017eivatel implant\u00e1tu. RONDO 2. Mlad\u00e1 Boleslav<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-4 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/michaela\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/vit\/\" aria-label=\"V\u00edt\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"883\" height=\"847\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27883%27%20height%3D%27847%27%20viewBox%3D%270%200%20883%20847%27%3E%3Crect%20width%3D%27883%27%20height%3D%27847%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688-200x192.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688-400x384.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688-600x576.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688-800x767.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Vit-2-e1778572973688.jpg 883w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-4 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-10 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>V\u00edt<\/p>\n<\/div><div class=\"fusion-text fusion-text-11 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Jsem oboustrann\u00fd u\u017eivatel implant\u00e1tu (RONDO 2). Implantace v roce 2014. D\u011b\u010d\u00edn<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-5 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/vit\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/mirka\/\" aria-label=\"Mirka\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Miroslava-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-5 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-12 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Mirka<\/p>\n<\/div><div class=\"fusion-text fusion-text-13 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Jsem u\u017eivatel implant\u00e1tu (oboustrann\u00fd). \nRONDO 2. \nMlad\u00e1 Boleslav<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-6 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/mirka\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two ys-margin\" style=\"--awb-text-color:#3d3b3b;--awb-margin-top:30px;--awb-margin-bottom:28px;--awb-font-size:45px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;DM Serif Text&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;--fontSize:45;line-height:1.4;\">Na\u0161i sluchov\u00ed poradci ze Slovenska v\u00e1m tak\u00e9 r\u00e1di pomohou.<\/h2><\/div><div class=\"fusion-post-cards fusion-post-cards-2 fusion-grid-archive fusion-grid-columns-3\" style=\"--awb-column-spacing:20px;--awb-dots-align:center;--awb-columns:3;--awb-active-filter-border-size:3px;--awb-filters-height:36px;--awb-row-spacing:20px;--awb-columns-medium:33.3333%;--awb-columns-small:100%;\"><ul class=\"fusion-grid fusion-grid-3 fusion-flex-align-items-stretch fusion-grid-posts-cards\"><li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/katarina\/\" aria-label=\"Katar\u00edna\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Katarina-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-6 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-14 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Katar\u00edna<\/p>\n<\/div><div class=\"fusion-text fusion-text-15 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Pou\u017e\u00edvate\u013eka kochle\u00e1rneho implant\u00e1tu a na\u010d\u00favacieho pr\u00edstroja. SONNET 2. Bratislava<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-7 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/katarina\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/peter\/\" aria-label=\"Peter\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Peter-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-7 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-16 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Peter<\/p>\n<\/div><div class=\"fusion-text fusion-text-17 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Otec die\u0165a\u0165a s KI. SONNET2, sk\u00fasenosti s RONDO3. Bratislava<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-8 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/peter\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<li class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion-flex-column post-card fusion-grid-column fusion-post-cards-grid-column\" style=\"--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-classic-product-image-wrapper fusion-woo-product-image fusion-post-card-image fusion-post-card-image-1\" data-layout=\"static\"><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/lifelonghearing.com\/cs\/partner\/miroslava\/\" aria-label=\"Miroslava\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1916\" height=\"1437\" src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-scaled.jpg\" class=\"attachment-full size-full lazyload wp-post-image\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271916%27%20height%3D%271437%27%20viewBox%3D%270%200%201916%201437%27%3E%3Crect%20width%3D%271916%27%20height%3D%271437%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-scaled.jpg\" data-srcset=\"https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-200x150.jpg 200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-400x300.jpg 400w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-600x450.jpg 600w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-800x600.jpg 800w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-1200x900.jpg 1200w, https:\/\/lifelonghearing.com\/cs\/wp-content\/uploads\/sites\/8\/2025\/03\/Zeman-Family-scaled.jpg 1916w\" data-sizes=\"auto\" \/>\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n<\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-8 fusion_builder_column_inner_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:30px;--awb-padding-right:40px;--awb-padding-bottom:30px;--awb-padding-left:40px;--awb-padding-top-small:20px;--awb-padding-right-small:20px;--awb-padding-bottom-small:20px;--awb-padding-left-small:20px;--awb-bg-color:#f9f9f9;--awb-bg-color-hover:#f9f9f9;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-18 fusion-text-no-margin\" style=\"--awb-font-size:20px;--awb-text-color:#000000;--awb-margin-bottom:5px;--awb-text-font-family:&quot;Open Sans&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Miroslava<\/p>\n<\/div><div class=\"fusion-text fusion-text-19 fusion-text-no-margin\" style=\"--awb-text-color:#515151;--awb-margin-bottom:10px;\"><p>Mama nepo\u010duj\u00faceho die\u0165a\u0165a s dvoma KI. SONNET2, sk\u00fasenosti s RONDO3. Bratislava<\/p>\n<\/div><div style=\"text-align:left;\"><a class=\"fusion-button button-flat button-large button-custom fusion-button-default button-9 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#5ebfbb;--button_border_color:#5ebfbb;--button_accent_hover_color:rgba(61,59,59,0.8);--button_border_hover_color:rgba(61,59,59,0.8);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_margin-right:0px;--button_margin-bottom:0px;--button_margin-left:-30px;\" target=\"_self\" href=\"https:\/\/lifelonghearing.com\/cs\/partner\/miroslava\/\"><span class=\"fusion-button-text\">KONTAKTOVA\u0164<\/span><i class=\"fa-arrow-right fas button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div><\/li>\n<\/ul><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-32573","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ambasadori Sluchu - Czech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ambasadori Sluchu - Czech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/\" \/>\n<meta property=\"og:site_name\" content=\"Czech\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T08:57:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/\",\"url\":\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/\",\"name\":\"Ambasadori Sluchu - Czech\",\"isPartOf\":{\"@id\":\"https:\/\/lifelonghearing.com\/cs\/#website\"},\"datePublished\":\"2025-03-29T10:32:02+00:00\",\"dateModified\":\"2026-03-03T08:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lifelonghearing.com\/cs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ambasadori Sluchu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lifelonghearing.com\/cs\/#website\",\"url\":\"https:\/\/lifelonghearing.com\/cs\/\",\"name\":\"Czech\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lifelonghearing.com\/cs\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ambasadori Sluchu - Czech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/","og_locale":"en_US","og_type":"article","og_title":"Ambasadori Sluchu - Czech","og_url":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/","og_site_name":"Czech","article_modified_time":"2026-03-03T08:57:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/","url":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/","name":"Ambasadori Sluchu - Czech","isPartOf":{"@id":"https:\/\/lifelonghearing.com\/cs\/#website"},"datePublished":"2025-03-29T10:32:02+00:00","dateModified":"2026-03-03T08:57:13+00:00","breadcrumb":{"@id":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lifelonghearing.com\/cs\/ambasadori-sluchu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lifelonghearing.com\/cs\/"},{"@type":"ListItem","position":2,"name":"Ambasadori Sluchu"}]},{"@type":"WebSite","@id":"https:\/\/lifelonghearing.com\/cs\/#website","url":"https:\/\/lifelonghearing.com\/cs\/","name":"Czech","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifelonghearing.com\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/pages\/32573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/comments?post=32573"}],"version-history":[{"count":42,"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/pages\/32573\/revisions"}],"predecessor-version":[{"id":33243,"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/pages\/32573\/revisions\/33243"}],"wp:attachment":[{"href":"https:\/\/lifelonghearing.com\/cs\/wp-json\/wp\/v2\/media?parent=32573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}